{"id":23060,"date":"2025-02-25T11:34:09","date_gmt":"2025-02-25T11:34:09","guid":{"rendered":"https:\/\/clearingtheair.eu\/post\/frankreich-ist-das-zweite-eu-land-das-wegwerfzigaretten-verbietet\/"},"modified":"2025-02-25T11:36:22","modified_gmt":"2025-02-25T11:36:22","slug":"frankreich-ist-das-zweite-eu-land-das-wegwerfzigaretten-verbietet","status":"publish","type":"post","link":"https:\/\/clearingtheair.eu\/de\/post\/frankreich-ist-das-zweite-eu-land-das-wegwerfzigaretten-verbietet\/","title":{"rendered":"Frankreich ist das zweite EU-Land, das Wegwerfzigaretten verbietet"},"content":{"rendered":"<div class=\"clear-before-content-2\" style=\"margin-top: 20px;margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"clear-3027747075\"><a href=\"https:\/\/www.broughton-group.com\/nicotine?utm_campaign=43296353-Clearing%20the%20Air%20PPC%20Campaign%20-%202026&#038;utm_source=ppc&#038;utm_medium=Paid%20Ads\" aria-label=\"728 x 90 (2)\"><img src=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png\" alt=\"\"  srcset=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png 728w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-300x37.png 300w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-370x46.png 370w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-600x74.png 600w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><strong>Frankreich ist das zweite Land der Europ\u00e4ischen Union, das Einwegdampfer verbietet.  <\/strong><\/p>\n\n<p>Das Gesetz wurde vom franz\u00f6sischen Senat nach einer letzten Parlamentsabstimmung am Donnerstag verabschiedet. Es kommt nach einem \u00e4hnlichen Verbot in Belgien, das am 1. Januar in Kraft trat.   <\/p>\n\n<p><a href=\"https:\/\/www.senat.fr\/leg\/ppl24-263.html\" rel=\"nofollow noopener\" target=\"_blank\">Die ge\u00e4nderte Version<\/a> des Gesetzentwurfs in Frankreich verbietet die Herstellung, die Vermarktung, den Vertrieb und die Lieferung von Einweg-Vapes.  <\/p>\n\n<p><strong>Ge\u00e4nderte Definition von Einwegvapes<\/strong><\/p>\n\n<p>Die neue Gesetzgebung definiert Einwegdampfer als &#8222;mit einer Fl\u00fcssigkeit vorgef\u00fcllt und nicht nachf\u00fcllbar, unabh\u00e4ngig davon, ob sie einen wiederaufladbaren Akku haben oder nicht&#8220;. Dies ist Berichten zufolge eine Reaktion auf die Meinung von Ausschussmitgliedern, dass der Gesetzestext den Fortschritten in der Vape-Technologie Rechnung tragen m\u00fcsse.   <\/p>\n\n<p>Die Europ\u00e4ische Kommission, die Exekutive der EU, die neuen Gesetzen der Mitgliedstaaten zustimmen muss, die sich auf die Wirtschaft des EU-Binnenmarktes auswirken k\u00f6nnten, gab im September gr\u00fcnes Licht f\u00fcr das Gesetz.  <\/p>\n\n<p>&#8222;Es ist ein gro\u00dfer Sieg in einem zweigleisigen Kampf, den wir gef\u00fchrt haben: ein Kampf f\u00fcr die Umwelt gegen die umweltsch\u00e4dlichen Lithiumbatterien in diesen &#8218;Puffs&#8216; und ein Kampf f\u00fcr die Gesundheit unserer Schulkinder&#8220;, <a href=\"https:\/\/www.lemonde.fr\/en\/france\/article\/2025\/02\/13\/french-parliament-votes-to-ban-disposable-e-cigarettes_6738129_7.html#:~:text=The%20French%20parliament%20on%20Thursday,in%20the%20Senate%20upper%20house\" rel=\"nofollow noopener\" target=\"_blank\">sagte die Verfasserin des Gesetzes, die Abgeordnete Francesca Pasquini, gegen\u00fcber Agence France-Presse<\/a>.<\/p>\n\n<p><strong>&#8218;Ein Schritt in die falsche Richtung&#8216;<\/strong><\/p>\n\n<p>Vape-Bef\u00fcrworter und Anti-Raucher-Aktivisten haben die neue Gesetzgebung jedoch als einen &#8222;Schritt in die falsche Richtung&#8220; kritisiert.<\/p>\n\n<p>Michael Landl, Direktor der World Vapers&#8216; Alliance, sagte:  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8222;Die Prohibition funktioniert nicht. Das hat sie nie und wird sie auch nie. Ein Verbot von Einwegdampfern wird die Nachfrage nicht beseitigen, sondern sie von den regulierten M\u00e4rkten auf den Schwarzmarkt verlagern, was negative, unbeabsichtigte Folgen f\u00fcr die \u00f6ffentliche Gesundheit hat.&#8220;<\/p>\n<\/blockquote>\n\n<p><strong>Verbot von Nikotinbeuteln<\/strong><\/p>\n\n<p>Inzwischen <a href=\"https:\/\/clearingtheair.eu\/en\/post\/france-one-step-closer-to-banning-nicotine-pouches-and-disposable-vapes\/\">ist auch Frankreich dabei, Nikotinbeutel zu verbieten<\/a>. Anfang dieses Monats wurde ein Gesetzesentwurf zum Verbot dieser Produkte vom Oberhaus des franz\u00f6sischen Senats gebilligt und r\u00fcckte damit in greifbare N\u00e4he.   <\/p>\n\n<p>Derzeit enth\u00e4lt der Gesetzentwurf Vorschl\u00e4ge zur Regulierung statt zum Verbot von Nikotinbeuteln durch eine Begrenzung ihrer St\u00e4rke und h\u00f6here Steuern. Der Senat ist jedoch bestrebt, diese Vorschl\u00e4ge zu streichen und stattdessen ein vollst\u00e4ndiges Verbot einzuf\u00fchren. <\/p>\n\n<p>In der <a href=\"https:\/\/www.senat.fr\/leg\/ppl24-263.html\" rel=\"nofollow noopener\" target=\"_blank\">neuen \u00c4nderung<\/a> hei\u00dft es: &#8222;Das Ziel dieser \u00c4nderung ist das Verbot von Nikotinbeuteln gem\u00e4\u00df den Ank\u00fcndigungen der Ministerin f\u00fcr Gesundheit und Zugang zur Gesundheitsversorgung, Genevi\u00e8ve Darrieusecq, vom 29. Oktober 2024.&#8220;<\/p>\n\n<p><strong>Erh\u00f6hung der Steuer auf E-LiquidsAuch<\/strong>im Oktober wurde bekannt, dass <a href=\"https:\/\/clearingtheair.eu\/en\/post\/france-set-to-hike-e-liquid-tax-by-38\/\">Frankreich die Steuer auf E-Liquids um satte 38 Prozent erh\u00f6hen will<\/a>. Laut der f\u00fchrenden franz\u00f6sischen Organisation <a href=\"https:\/\/fivape.org\/en\/assemblee-nationale-taxe-sur-la-vape-adoptee-augmentation-des-prix-du-tabac-rejetee\/#:~:text=In%20short%2C%20a%20majority%20of,is%20more%20alarming%20than%20ever.\" rel=\"nofollow noopener\" target=\"_blank\">FiVape<\/a> plant die franz\u00f6sische Regierung, eine Pauschalsteuer von 0,15 \u20ac pro Milliliter E-Liquid zu erheben, unabh\u00e4ngig davon, ob es Nikotin enth\u00e4lt oder nicht. <\/p>\n<div class=\"clear-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"clear-2894410084\"><a href=\"https:\/\/www.broughton-group.com\/nicotine?utm_campaign=43296353-Clearing%20the%20Air%20PPC%20Campaign%20-%202026&#038;utm_source=ppc&#038;utm_medium=Paid%20Ads\" aria-label=\"728 x 90 (2)\"><img src=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png\" alt=\"\"  srcset=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png 728w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-300x37.png 300w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-370x46.png 370w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-600x74.png 600w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Frankreich ist das zweite Land der Europ\u00e4ischen Union, das Einwegdampfer verbietet. Das Gesetz wurde vom franz\u00f6sischen Senat nach einer letzten Parlamentsabstimmung am Donnerstag verabschiedet. Es kommt nach einem \u00e4hnlichen Verbot in Belgien, das am 1. Januar in Kraft trat. Die ge\u00e4nderte Version&hellip;<\/p>\n","protected":false},"author":990002,"featured_media":23053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[265,268],"tags":[411,327,376],"slider":[],"class_list":["post-23060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislation","category-news","tag-europaische-union","tag-france","tag-nikotin"],"_links":{"self":[{"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/posts\/23060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/users\/990002"}],"replies":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/comments?post=23060"}],"version-history":[{"count":1,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/posts\/23060\/revisions"}],"predecessor-version":[{"id":23061,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/posts\/23060\/revisions\/23061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/media\/23053"}],"wp:attachment":[{"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/media?parent=23060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/categories?post=23060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/tags?post=23060"},{"taxonomy":"slider","embeddable":true,"href":"https:\/\/clearingtheair.eu\/de\/wp-json\/wp\/v2\/slider?post=23060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}