{"id":26856,"date":"2025-09-30T09:22:56","date_gmt":"2025-09-30T09:22:56","guid":{"rendered":"https:\/\/clearingtheair.eu\/post\/la-reorganizacion-de-las-licencias-podria-bloquear-el-acceso-a-los-vaporizadores-advierten-los-minoristas\/"},"modified":"2025-09-30T09:23:15","modified_gmt":"2025-09-30T09:23:15","slug":"la-reorganizacion-de-las-licencias-podria-bloquear-el-acceso-a-los-vaporizadores-advierten-los-minoristas","status":"publish","type":"post","link":"https:\/\/clearingtheair.eu\/es\/post\/la-reorganizacion-de-las-licencias-podria-bloquear-el-acceso-a-los-vaporizadores-advierten-los-minoristas\/","title":{"rendered":"La reorganizaci\u00f3n de las licencias podr\u00eda bloquear el acceso a los vaporizadores, advierten los minoristas"},"content":{"rendered":"<div class=\"clear-before-content-2\" style=\"margin-top: 20px;margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"clear-2685470563\"><a data-no-instant=\"1\" href=\"https:\/\/www.broughton-group.com\/nicotine?utm_campaign=43296353-Clearing%20the%20Air%20PPC%20Campaign%20-%202026&#038;utm_source=ppc&#038;utm_medium=Paid%20Ads\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"728 x 90 (2)\"><img src=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png\" alt=\"\"  srcset=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png 728w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-300x37.png 300w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-370x46.png 370w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-600x74.png 600w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p class=\"wp-block-paragraph\"><strong>El acceso a los vapes podr\u00eda quedar cortado para miles de fumadores en virtud de las nuevas normas gubernamentales sobre concesi\u00f3n de licencias. Los minoristas y la industria del vaping advierten de que la medida podr\u00eda aumentar el consumo de tabaco e impulsar el mercado negro. <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">El <a href=\"https:\/\/clearingtheair.eu\/en\/post\/tobacco-and-vapes-bill-moves-closer-to-becoming-law\/\">proyecto de ley sobre tabaco y vapor<\/a>es, actualmente en la C\u00e1mara de los Lores, obligar\u00eda a todas las tiendas que vendan tabaco o vapores a solicitar una licencia, y se espera que las normas entren en vigor a partir de enero de 2027.  <\/p>\n\n<p class=\"wp-block-paragraph\">La consultora de licencias Jane Gilliead dijo que es probable que el marco refleje la Ley de Licencias de 2003, que bloquea la venta de alcohol en \u00abzonas de impacto acumulativo\u00bb relacionadas con comportamientos antisociales o cerca de centros escolares.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>No hay \u00abderechos adquiridos\u00bb para los vendedores de vaporizadores<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">\u00abSi nos fijamos en [la Ley de 2003] como gu\u00eda, tenemos condiciones estrictas para los cuatro objetivos de la licencia, y hay cosas que se combinan, como la planificaci\u00f3n\u00bb, dijo.  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00abObservando las normas que se han promovido a partir de los fundamentos de la Ley de Licencias y teniendo eso en cuenta, hablan de zonas en las que no permitir\u00e1n zonas para fumadores, o no permitir\u00e1n que la gente tenga la licencia por estar cerca de escuelas\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">A diferencia de las licencias de alcohol, es poco probable que los vendedores existentes se beneficien de los \u00abderechos adquiridos\u00bb, que proteg\u00edan autom\u00e1ticamente a los minoristas de alcohol en 2003. Gilliead dijo que los ayuntamientos no tienen registros de las tiendas que venden tabaco o vapores, lo que significa que todos los puntos de venta tendr\u00e1n que presentar solicitudes completas. Predijo un periodo de seis meses a partir de julio de 2026, y la aplicaci\u00f3n el 1 de enero de 2027.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>El r\u00e9gimen no debe castigar a los minoristas responsables<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">El director ejecutivo de la Asociaci\u00f3n de Tiendas de Conveniencia, James Lowman, advirti\u00f3: \u00abEsperamos que el proyecto de ley sobre tabaco y vapores incluya detalles de un sistema de concesi\u00f3n de licencias que podr\u00eda restringir las licencias concedidas a los minoristas por su proximidad a escuelas y a otros negocios similares por motivos de impacto acumulativo.  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00abLa capacidad de las tiendas de conveniencia para ofrecer diversos productos y servicios se ver\u00eda mermada si no obtuvieran una licencia para vender estos productos. Es crucial que un sistema de licencias funcione eficazmente para detener a los comerciantes deshonestos sin castigar indebidamente a los minoristas responsables.\u00bb<\/p>\n\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n de la Industria del Vapeo del Reino Unido (UKVIA) tambi\u00e9n ha arremetido contra el programa \u00abPride in Place\u00bb del primer ministro Keir Starmer, que propone dar poderes a las comunidades para bloquear las tiendas de vapeo junto a las casas de apuestas y otros negocios \u00abno deseados\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">El director general de la UKVIA, John Dunne, declar\u00f3 \u00abEste anuncio puede ser un buen titular, pero debemos dar prioridad a una pol\u00edtica s\u00f3lida sobre las frases hechas cuando se trata de proteger la salud p\u00fablica.  <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abEl vapeo es el m\u00e9todo m\u00e1s eficaz para ayudar a los fumadores adultos a dejar de fumar, supone s\u00f3lo una \u00ednfima parte de los riesgos para la salud del tabaquismo y, sin embargo, casi seis de cada diez adultos creen err\u00f3neamente que es tan perjudicial o m\u00e1s que fumar.\u00bb<\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Perjudicar a las comunidades  <\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Y a\u00f1adi\u00f3: \u00abVincular las tiendas de vapeo a la categor\u00eda de &#8216;tiendas no deseadas&#8217; con locales como las casas de apuestas y los falsos barberos, perjudicar\u00e1 a las comunidades al aumentar las tasas de tabaquismo. Las tiendas especializadas en vapeo prestan un servicio muy necesario a sus comunidades al educar a los fumadores sobre formas mucho m\u00e1s seguras de consumir tabaco.\u00bb<\/p>\n\n<p class=\"wp-block-paragraph\">Dunne dijo que la concesi\u00f3n de licencias podr\u00eda ser una fuerza para el bien si se dise\u00f1ara para perseguir a los comerciantes deshonestos: \u00abLa concesi\u00f3n de licencias para vapear podr\u00eda financiar brigadas espec\u00edficas de funcionarios de las normas de comercio por valor de m\u00e1s de 50 millones de libras al a\u00f1o sin coste adicional para el erario p\u00fablico y, si se respaldara con multas de 10.000 libras para quienes vendan a ni\u00f1os o vendan productos il\u00edcitos, los minoristas deshonestos tendr\u00edan un enorme incentivo para mantenerse dentro de la ley.\u00bb<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">advirti\u00f3: \u00abCrear barreras innecesarias a la venta responsable de vape corre el riesgo de empujar a la gente a volver a fumar o a caer en manos del mercado il\u00edcito, que es lo que nadie quiere\u00bb.<\/p>\n<\/blockquote>\n<div class=\"clear-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"clear-2825077056\"><a data-no-instant=\"1\" href=\"https:\/\/www.broughton-group.com\/nicotine?utm_campaign=43296353-Clearing%20the%20Air%20PPC%20Campaign%20-%202026&#038;utm_source=ppc&#038;utm_medium=Paid%20Ads\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"728 x 90 (2)\"><img src=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png\" alt=\"\"  srcset=\"https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2.png 728w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-300x37.png 300w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-370x46.png 370w, https:\/\/clearingtheair.eu\/wp-content\/uploads\/2026\/04\/728-x-90-2-600x74.png 600w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>El acceso a los vapes podr\u00eda quedar cortado para miles de fumadores en virtud de las nuevas normas gubernamentales sobre concesi\u00f3n de licencias. Los minoristas y la industria del vaping advierten de que la medida podr\u00eda aumentar el consumo de tabaco e&hellip;<\/p>\n","protected":false},"author":990002,"featured_media":26854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[],"slider":[],"class_list":["post-26856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/posts\/26856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/users\/990002"}],"replies":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/comments?post=26856"}],"version-history":[{"count":1,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/posts\/26856\/revisions"}],"predecessor-version":[{"id":26857,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/posts\/26856\/revisions\/26857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/media\/26854"}],"wp:attachment":[{"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/media?parent=26856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/categories?post=26856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/tags?post=26856"},{"taxonomy":"slider","embeddable":true,"href":"https:\/\/clearingtheair.eu\/es\/wp-json\/wp\/v2\/slider?post=26856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}